{"id":38364,"date":"2021-03-01T15:34:04","date_gmt":"2021-03-01T13:34:04","guid":{"rendered":"https:\/\/millavintage.com\/2023\/01\/15\/ziua-femeii-5-filme-despre-femei-puternice\/"},"modified":"2023-01-16T19:32:51","modified_gmt":"2023-01-16T17:32:51","slug":"ziua-femeii-5-filme-despre-femei-puternice","status":"publish","type":"post","link":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/","title":{"rendered":"Festa della donna: 5 film su donne forti"},"content":{"rendered":"<p>Donna. Il mondo sarebbe ancora un mondo senza donne? No. Perch\u00e9 tutto ruota intorno alla donna, questo essere fragile, senza molta forza fisica, ma con molta forza spirituale, forza creativa, forza dominante e forza di rendere il mondo pi\u00f9 colorato. Donna, una parola che esprime amore, dolcezza e sincerit\u00e0, sensibilit\u00e0, fragilit\u00e0, forza, sorrisi, lacrime, speranza, compassione, comprensione, adattamento, pazienza, umorismo, tristezza, testardaggine, sottomissione, cura, generosit\u00e0. Donna &#8211; madre, figlia, moglie, nonna, sorella, amante, amica. Quanti compiti sono attribuiti alla donna e quanto pu\u00f2 essere ricca, solo per il fatto di esistere. Per questo la donna \u00e8 lodata da tutti i grandi artisti del mondo: la donna si trova nei pensieri dei poeti, la donna \u00e8 la musa dei pittori, dei fotografi, la donna \u00e8 l&#8217;eroina principale di molti registi, e non solo.<\/p>\n<p>Detto questo, ecco alcuni film in cui le donne sono in primo piano, donne forti, donne in tutti i loro aspetti.\u00a0Ecco quindi cinque film dedicati a lei, la donna.<\/p>\n<h2 class=\"entry-title\"><a href=\"https:\/\/millavintage.com\/it\/2016\/01\/16\/o-lista-cu-filme-pe-care-sa-le-vezi-in-2016\/\">Una lista di film da vedere nel 2016<\/a><\/h2>\n<h2 style=\"text-align: justify;\">Bread and rose<\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9293\" src=\"https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/3.jpg\" alt=\"3.jpg\" width=\"1200\" height=\"797\" srcset=\"https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/3.jpg 1200w, https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/3-150x100.jpg 150w, https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/3-300x199.jpg 300w, https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/3-1024x680.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>\u00c8 la storia di una donna, di nome Maya, che attraversa illegalmente il confine messicano per entrare negli Stati Uniti. Maya, energica e determinata, lavora come donna delle pulizie in un edificio, diventando una delle schiave illegali in America Latina o nei Paesi dell&#8217;Est, sottopagata e priva di diritti sociali legali. Finch\u00e9 un giorno un attivista sindacale non d\u00e0 un&#8217;altra dimensione alla realt\u00e0, la sua unica possibilit\u00e0 di vita umana \u00e8 l&#8217;organizzazione.<\/p>\n<h2 style=\"text-align: justify;\">Frida<\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9303\" src=\"https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/salma-hayek-frida.jpg\" alt=\"salma-hayek-frida\" width=\"1200\" height=\"802\" srcset=\"https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/salma-hayek-frida.jpg 1200w, https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/salma-hayek-frida-150x100.jpg 150w, https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/salma-hayek-frida-300x201.jpg 300w, https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/salma-hayek-frida-1024x684.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>Il film \u00e8 la storia della vita di Frida Kahlo. Una storia ambientata in un contesto di storie d&#8217;amore e finali infelici. Frida ha vissuto una vita audace e senza compromessi, sfidando i pregiudizi, rivoluzionando l&#8217;arte, la politica e la vita sessuale.<\/p>\n<h2 style=\"text-align: justify;\">It&#8217;s a free world<\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9319\" src=\"https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/itsafreeworld1.jpg\" alt=\"itsafreeworld1\" width=\"1400\" height=\"934\" srcset=\"https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/itsafreeworld1.jpg 1400w, https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/itsafreeworld1-150x100.jpg 150w, https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/itsafreeworld1-300x200.jpg 300w, https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/itsafreeworld1-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/>Angie viene licenziata da un&#8217;agenzia di reclutamento dopo aver causato uno scandalo pubblico. Ma non si arrende e avvia una nuova agenzia per conto suo. Con la cucina dell&#8217;azienda e una schiera di immigrati alla disperata ricerca di un lavoro per mantenere le proprie famiglie, l&#8217;opportunit\u00e0 di Angie \u00e8 enorme, soprattutto perch\u00e9 ha un buon senso delle esigenze del mercato del lavoro.<\/p>\n<h2 class=\"entry-title\"><a href=\"https:\/\/millavintage.com\/it\/2019\/01\/15\/filme-de-dragoste-pe-care-sa-le-vedeti-impreuna-de-dragobete\/\">I film d\u2019amore da guardare insieme a San Valentino<\/a><\/h2>\n<h2 style=\"text-align: justify;\">Elles<\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9328\" src=\"https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/elles-e1673890335600.jpg\" alt=\"elles\" width=\"1280\" height=\"720\" \/>\u00c8 la storia di Anne, madre di due figli e giornalista d&#8217;inchiesta per la rivista Elle, che viene incaricata di scrivere un articolo sulle prostitute studentesche. I suoi incontri con due giovani prostitute, Alicja e Charlotte, toccheranno Anne nel profondo e la faranno riflettere sulle sue convinzioni riguardo al denaro, al sesso e alla famiglia.<\/p>\n<h2 style=\"text-align: justify;\">Sleeping Beauty<\/h2>\n<h1 class=\"scheda-film\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9341\" src=\"https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/sleeping_beauty021.jpg\" alt=\"sleeping_beauty021\" width=\"2048\" height=\"1156\" srcset=\"https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/sleeping_beauty021.jpg 2048w, https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/sleeping_beauty021-150x85.jpg 150w, https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/sleeping_beauty021-300x169.jpg 300w, https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/sleeping_beauty021-1024x578.jpg 1024w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/h1>\n<p>Lucy (Emily Browning) \u00e8 la protagonista di questo film. Da giovane studentessa, per pagarsi gli studi, Lucy diventa una piccola cavia per esperimenti medici, ma finisce anche per prostituirsi in vari luoghi, finch\u00e9 non le viene offerto un lavoro in una misteriosa villa, dove i ricchi ospiti possono abbandonarsi ai loro piaceri in un gioco erotico chiamato Bella Addormentata. In questo film scoprirete un mondo segreto di bellezza e desiderio.<\/p>\n<h4>Seguitemi su\u00a0 <a href=\"https:\/\/www.instagram.com\/liudmila.carta\/\">Instagram<\/a> e\u00a0<a href=\"https:\/\/www.facebook.com\/millavintage\/?__tn__=kC-%20R&amp;eid=ARALIWYR4gA5f_zapWcQjCTjZVe2fykLkU5fJITo6dfLeDESkl7qy55lROqcBtZvxrUXn1ScqyUySvVW&amp;hc_ref=ARQoIMlZt-lRs9cpxYGKDiRUyUjrAIbFRmkHAqEdMbH5Luvtgj1Kt7gLICnHA0g5lHg&amp;fref=nf&amp;__xts__[0]=68.ARDyUiMLQZiXZC2yRPz_2AsAgb0HDU1Gh5Nmi_wxgII90NoBKflEQuyZ49xSKufnXa2X5HYk-jrWvTZ0iDIwg6KDoeLu1BApkfUdfOQIGvASfe1EnRvkUVnLVPBcVPFisYMGQgQl_OBLnKReI0wmq1N1n5z2nFYuvx5bHT0vB6OhhyhpWyfW3hgnJNfnr5zngZdjm5j9V8aw_KB2tsSb6qc3AiCn6mbsZBQvzffwWpEpnRE39HEE6kL6adxlfcleVdb2gyQ-RM_LMEz0n8xkzXpwEopsdPoY4ZmsjGQBKOQJ6icQSnSI24Wca_JhdhoUjOHMXRDOBia3h8Y24qYqnWE04I0a1VdZ9njk2pvO&amp;__xts__[1]=68.ARBeX48qxLvz1JEUfibzrC6nwGdjwg04twoGr8azBrumVKUijTAN2S2-TJmSl46s6NmaoyEYLaxr4M7BWBqicRFHtzQltBFE287A_3t9JGgvdJyfu4z1dXUL0u_MNuOepBiJYfgTywd-ZnxC7809CH4eqQQAMFOFmm4A5Nkml34g2G6kpp1rcGYHrHq39xUtwIXCvf1y0RSYX3rLz-ZvCW0wiWft1PoTnTj7JmU6OWad_oowI4FvLEDvFjm_HMfz0avDO55i2lgOCbro7dP3rRRkdBxnV4ACkYTRI81WSxDvAyF0qkj4kA5TieYcuESqO5C9LjxN_J9KtNlSKkYewDXaRsAgoqVk8orqgi6s\">Facebook<\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Donna. Il mondo sarebbe ancora un mondo senza donne? No. Perch\u00e9 tutto ruota intorno alla donna, questo essere fragile, senza molta forza fisica, ma con molta forza spirituale, forza creativa,&hellip;<\/div>\n<div class=\"post-more\"><a href=\"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/\" class=\"btn btn-primary btn-effect\"><span>Visualizza Post<\/span><span><i class=\"icon icon-arrow-right\"><\/i><\/span><\/a><\/div>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAowyturDA:productID":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_bluesky_share_type":"","_mastodon_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[4294],"tags":[],"class_list":["post-38364","post","type-post","status-publish","format-standard","hentry","category-film"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Alcuni film consigliati in cui le donne sono in primo piano, donne forti, donne in tutti i loro aspetti. Ecco quindi cinque film dedicati a lei, la donna\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"Liudmila Carta\"\/>\n\t<meta name=\"google-site-verification\" content=\"el3VXTq1o448btMtWKmhCQ9M8c3zrH5p7cA-2j5L3IE\" \/>\n\t<meta name=\"p:domain_verify\" content=\"62debaadc0d84021b4726ff317ad7360\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Millavintage\" \/>\n\t\t<meta property=\"og:type\" content=\"blog\" \/>\n\t\t<meta property=\"og:title\" content=\"Festa della donna: 5 film su donne forti | Millavintage\" \/>\n\t\t<meta property=\"og:description\" content=\"Alcuni film consigliati in cui le donne sono in primo piano, donne forti, donne in tutti i loro aspetti. Ecco quindi cinque film dedicati a lei, la donna\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/millavintage.com\/wp-content\/uploads\/2021\/10\/leggings-11.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/millavintage.com\/wp-content\/uploads\/2021\/10\/leggings-11.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@millavintage\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Festa della donna: 5 film su donne forti | Millavintage\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Alcuni film consigliati in cui le donne sono in primo piano, donne forti, donne in tutti i loro aspetti. Ecco quindi cinque film dedicati a lei, la donna\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/millavintage.com\/wp-content\/uploads\/2021\/10\/leggings-11.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/ziua-femeii-5-filme-despre-femei-puternice\\\/#article\",\"name\":\"Festa della donna: 5 film su donne forti | Millavintage\",\"headline\":\"Festa della donna: 5 film su donne forti\",\"author\":{\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/author\\\/liudmilacarta\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/millavintage.com\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/3.jpg\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/ziua-femeii-5-filme-despre-femei-puternice\\\/#articleImage\",\"width\":1200,\"height\":797},\"datePublished\":\"2021-03-01T15:34:04+02:00\",\"dateModified\":\"2023-01-16T19:32:51+02:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/ziua-femeii-5-filme-despre-femei-puternice\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/ziua-femeii-5-filme-despre-femei-puternice\\\/#webpage\"},\"articleSection\":\"FILM, Opzionale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/ziua-femeii-5-filme-despre-femei-puternice\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/millavintage.com\\\/it\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/category\\\/film\\\/#listItem\",\"name\":\"FILM\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/category\\\/film\\\/#listItem\",\"position\":2,\"name\":\"FILM\",\"item\":\"https:\\\/\\\/millavintage.com\\\/it\\\/category\\\/film\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/ziua-femeii-5-filme-despre-femei-puternice\\\/#listItem\",\"name\":\"Festa della donna: 5 film su donne forti\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/ziua-femeii-5-filme-despre-femei-puternice\\\/#listItem\",\"position\":3,\"name\":\"Festa della donna: 5 film su donne forti\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/category\\\/film\\\/#listItem\",\"name\":\"FILM\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/#person\",\"name\":\"Liudmila Carta\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/ziua-femeii-5-filme-despre-femei-puternice\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a332a72336854cec3bc6a54670544ef0ede6a9058c00494a5c1c4ef622df6788?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Liudmila Carta\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/author\\\/liudmilacarta\\\/#author\",\"url\":\"https:\\\/\\\/millavintage.com\\\/it\\\/author\\\/liudmilacarta\\\/\",\"name\":\"Liudmila Carta\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/ziua-femeii-5-filme-despre-femei-puternice\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a332a72336854cec3bc6a54670544ef0ede6a9058c00494a5c1c4ef622df6788?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Liudmila Carta\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/ziua-femeii-5-filme-despre-femei-puternice\\\/#webpage\",\"url\":\"https:\\\/\\\/millavintage.com\\\/it\\\/ziua-femeii-5-filme-despre-femei-puternice\\\/\",\"name\":\"Festa della donna: 5 film su donne forti | Millavintage\",\"description\":\"Alcuni film consigliati in cui le donne sono in primo piano, donne forti, donne in tutti i loro aspetti. Ecco quindi cinque film dedicati a lei, la donna\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/ziua-femeii-5-filme-despre-femei-puternice\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/author\\\/liudmilacarta\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/author\\\/liudmilacarta\\\/#author\"},\"datePublished\":\"2021-03-01T15:34:04+02:00\",\"dateModified\":\"2023-01-16T19:32:51+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/millavintage.com\\\/it\\\/\",\"name\":\"Millavintage\",\"alternateName\":\"Liudmila Carta\",\"description\":\"Blog de mod\\u0103, frumuse\\u021be \\u0219i stil de via\\u021b\\u0103 italian\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/millavintage.com\\\/it\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Festa della donna: 5 film su donne forti | Millavintage","description":"Alcuni film consigliati in cui le donne sono in primo piano, donne forti, donne in tutti i loro aspetti. Ecco quindi cinque film dedicati a lei, la donna","canonical_url":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"google-site-verification":"el3VXTq1o448btMtWKmhCQ9M8c3zrH5p7cA-2j5L3IE","p:domain_verify":"62debaadc0d84021b4726ff317ad7360","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/#article","name":"Festa della donna: 5 film su donne forti | Millavintage","headline":"Festa della donna: 5 film su donne forti","author":{"@id":"https:\/\/millavintage.com\/it\/author\/liudmilacarta\/#author"},"publisher":{"@id":"https:\/\/millavintage.com\/it\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/millavintage.com\/wp-content\/uploads\/2016\/03\/3.jpg","@id":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/#articleImage","width":1200,"height":797},"datePublished":"2021-03-01T15:34:04+02:00","dateModified":"2023-01-16T19:32:51+02:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/#webpage"},"isPartOf":{"@id":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/#webpage"},"articleSection":"FILM, Opzionale"},{"@type":"BreadcrumbList","@id":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/millavintage.com\/it\/#listItem","position":1,"name":"Home","item":"https:\/\/millavintage.com\/it\/","nextItem":{"@type":"ListItem","@id":"https:\/\/millavintage.com\/it\/category\/film\/#listItem","name":"FILM"}},{"@type":"ListItem","@id":"https:\/\/millavintage.com\/it\/category\/film\/#listItem","position":2,"name":"FILM","item":"https:\/\/millavintage.com\/it\/category\/film\/","nextItem":{"@type":"ListItem","@id":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/#listItem","name":"Festa della donna: 5 film su donne forti"},"previousItem":{"@type":"ListItem","@id":"https:\/\/millavintage.com\/it\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/#listItem","position":3,"name":"Festa della donna: 5 film su donne forti","previousItem":{"@type":"ListItem","@id":"https:\/\/millavintage.com\/it\/category\/film\/#listItem","name":"FILM"}}]},{"@type":"Person","@id":"https:\/\/millavintage.com\/it\/#person","name":"Liudmila Carta","image":{"@type":"ImageObject","@id":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/a332a72336854cec3bc6a54670544ef0ede6a9058c00494a5c1c4ef622df6788?s=96&d=mm&r=g","width":96,"height":96,"caption":"Liudmila Carta"}},{"@type":"Person","@id":"https:\/\/millavintage.com\/it\/author\/liudmilacarta\/#author","url":"https:\/\/millavintage.com\/it\/author\/liudmilacarta\/","name":"Liudmila Carta","image":{"@type":"ImageObject","@id":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a332a72336854cec3bc6a54670544ef0ede6a9058c00494a5c1c4ef622df6788?s=96&d=mm&r=g","width":96,"height":96,"caption":"Liudmila Carta"}},{"@type":"WebPage","@id":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/#webpage","url":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/","name":"Festa della donna: 5 film su donne forti | Millavintage","description":"Alcuni film consigliati in cui le donne sono in primo piano, donne forti, donne in tutti i loro aspetti. Ecco quindi cinque film dedicati a lei, la donna","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/millavintage.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/#breadcrumblist"},"author":{"@id":"https:\/\/millavintage.com\/it\/author\/liudmilacarta\/#author"},"creator":{"@id":"https:\/\/millavintage.com\/it\/author\/liudmilacarta\/#author"},"datePublished":"2021-03-01T15:34:04+02:00","dateModified":"2023-01-16T19:32:51+02:00"},{"@type":"WebSite","@id":"https:\/\/millavintage.com\/it\/#website","url":"https:\/\/millavintage.com\/it\/","name":"Millavintage","alternateName":"Liudmila Carta","description":"Blog de mod\u0103, frumuse\u021be \u0219i stil de via\u021b\u0103 italian","inLanguage":"it-IT","publisher":{"@id":"https:\/\/millavintage.com\/it\/#person"}}]},"og:locale":"it_IT","og:site_name":"Millavintage","og:type":"blog","og:title":"Festa della donna: 5 film su donne forti | Millavintage","og:description":"Alcuni film consigliati in cui le donne sono in primo piano, donne forti, donne in tutti i loro aspetti. Ecco quindi cinque film dedicati a lei, la donna","og:url":"https:\/\/millavintage.com\/it\/ziua-femeii-5-filme-despre-femei-puternice\/","og:image":"https:\/\/millavintage.com\/wp-content\/uploads\/2021\/10\/leggings-11.jpg","og:image:secure_url":"https:\/\/millavintage.com\/wp-content\/uploads\/2021\/10\/leggings-11.jpg","og:image:width":800,"og:image:height":1200,"twitter:card":"summary_large_image","twitter:site":"@millavintage","twitter:title":"Festa della donna: 5 film su donne forti | Millavintage","twitter:description":"Alcuni film consigliati in cui le donne sono in primo piano, donne forti, donne in tutti i loro aspetti. Ecco quindi cinque film dedicati a lei, la donna","twitter:image":"https:\/\/millavintage.com\/wp-content\/uploads\/2021\/10\/leggings-11.jpg"},"aioseo_meta_data":{"post_id":"38364","title":"Festa della donna: 5 film su donne forti | #site_title","description":"Alcuni film consigliati in cui le donne sono in primo piano, donne forti, donne in tutti i loro aspetti. Ecco quindi cinque film dedicati a lei, la donna","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"blog","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"summary_large_image","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":{"id":"aioseo-article-63b3e4d734b87","slug":"article","graphName":"Article","label":"Articol","properties":{"type":"BlogPosting","name":"#post_title","headline":"#post_title","description":"#post_excerpt","image":"","keywords":"","author":{"name":"#author_name","url":"#author_url"},"dates":{"include":true,"datePublished":"","dateModified":""}}},"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-01-15 13:34:06","updated":"2025-11-17 19:09:35","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/millavintage.com\/it\/wp-json\/wp\/v2\/posts\/38364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/millavintage.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/millavintage.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/millavintage.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/millavintage.com\/it\/wp-json\/wp\/v2\/comments?post=38364"}],"version-history":[{"count":0,"href":"https:\/\/millavintage.com\/it\/wp-json\/wp\/v2\/posts\/38364\/revisions"}],"wp:attachment":[{"href":"https:\/\/millavintage.com\/it\/wp-json\/wp\/v2\/media?parent=38364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/millavintage.com\/it\/wp-json\/wp\/v2\/categories?post=38364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/millavintage.com\/it\/wp-json\/wp\/v2\/tags?post=38364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}